{"id":99,"date":"2017-10-28T11:39:18","date_gmt":"2017-10-28T11:39:18","guid":{"rendered":"http:\/\/actikare.com\/central-nj\/v2\/tutor\/dementia-care-2\/"},"modified":"2018-08-16T13:44:02","modified_gmt":"2018-08-16T17:44:02","slug":"recovery-home-care","status":"publish","type":"page","link":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/","title":{"rendered":"Recovery Care"},"content":{"rendered":"<h1>Recovery Home Care<\/h1>\n<p>Providing Recovery Home Care Services in Central New Jersey, New Jersey.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acti-Kare of Central New Jersey, NJ provides recovery home care services for surgery, accident and other disabilities &#8211; qualified caregivers &#8211; meals, personal care, house cleaning and more. <\/p>\n","protected":false},"author":1,"featured_media":207,"parent":0,"menu_order":29,"comment_status":"closed","ping_status":"closed","template":"template-tutor-inner.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-99","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recovery Care &amp; Recovery Home Care Services | Acti-Kare of Central New Jersey, NJ<\/title>\n<meta name=\"description\" content=\"Recovery Care &amp; Recovery Home Care Services.Acti-Kare of of Central New Jersey, NJ provides recovery care services for surgery, accident and other disabilities as well as recovery care assistance with meal prep, personal care, house cleaning and more to help assist you in recovery. Acti-Kare of of Central New Jersey, also provides recovery home care services in Middletown Township, Monroe Township and Princeton.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recovery Care &amp; Recovery Home Care Services | Acti-Kare of Central New Jersey, NJ\" \/>\n<meta property=\"og:description\" content=\"Recovery Care &amp; Recovery Home Care Services.Acti-Kare of of Central New Jersey, NJ provides recovery care services for surgery, accident and other disabilities as well as recovery care assistance with meal prep, personal care, house cleaning and more to help assist you in recovery. Acti-Kare of of Central New Jersey, also provides recovery home care services in Middletown Township, Monroe Township and Princeton.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/\" \/>\n<meta property=\"og:site_name\" content=\"Acti-Kare of Central New Jersey\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-16T17:44:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1349\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/\",\"url\":\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/\",\"name\":\"Recovery Care & Recovery Home Care Services | Acti-Kare of Central New Jersey, NJ\",\"isPartOf\":{\"@id\":\"https:\/\/actikare.com\/central-nj\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg\",\"datePublished\":\"2017-10-28T11:39:18+00:00\",\"dateModified\":\"2018-08-16T17:44:02+00:00\",\"description\":\"Recovery Care & Recovery Home Care Services.Acti-Kare of of Central New Jersey, NJ provides recovery care services for surgery, accident and other disabilities as well as recovery care assistance with meal prep, personal care, house cleaning and more to help assist you in recovery. Acti-Kare of of Central New Jersey, also provides recovery home care services in Middletown Township, Monroe Township and Princeton.\",\"breadcrumb\":{\"@id\":\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#primaryimage\",\"url\":\"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg\",\"contentUrl\":\"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg\",\"width\":1349,\"height\":571,\"caption\":\"Home Care Services in in Central New Jersey, NJ | In-Home Care Servicesi in Central New Jersey, NJ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/actikare.com\/central-nj\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recovery Care\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/actikare.com\/central-nj\/#website\",\"url\":\"https:\/\/actikare.com\/central-nj\/\",\"name\":\"Acti-Kare of Central New Jersey\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/actikare.com\/central-nj\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/actikare.com\/central-nj\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/actikare.com\/central-nj\/#organization\",\"name\":\"Acti-Kare of Central New Jersey\",\"url\":\"https:\/\/actikare.com\/central-nj\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/actikare.com\/central-nj\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/logo.png\",\"contentUrl\":\"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/logo.png\",\"width\":101,\"height\":60,\"caption\":\"Acti-Kare of Central New Jersey\"},\"image\":{\"@id\":\"https:\/\/actikare.com\/central-nj\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recovery Care & Recovery Home Care Services | Acti-Kare of Central New Jersey, NJ","description":"Recovery Care & Recovery Home Care Services.Acti-Kare of of Central New Jersey, NJ provides recovery care services for surgery, accident and other disabilities as well as recovery care assistance with meal prep, personal care, house cleaning and more to help assist you in recovery. Acti-Kare of of Central New Jersey, also provides recovery home care services in Middletown Township, Monroe Township and Princeton.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/","og_locale":"en_US","og_type":"article","og_title":"Recovery Care & Recovery Home Care Services | Acti-Kare of Central New Jersey, NJ","og_description":"Recovery Care & Recovery Home Care Services.Acti-Kare of of Central New Jersey, NJ provides recovery care services for surgery, accident and other disabilities as well as recovery care assistance with meal prep, personal care, house cleaning and more to help assist you in recovery. Acti-Kare of of Central New Jersey, also provides recovery home care services in Middletown Township, Monroe Township and Princeton.","og_url":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/","og_site_name":"Acti-Kare of Central New Jersey","article_modified_time":"2018-08-16T17:44:02+00:00","og_image":[{"width":1349,"height":571,"url":"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/","url":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/","name":"Recovery Care & Recovery Home Care Services | Acti-Kare of Central New Jersey, NJ","isPartOf":{"@id":"https:\/\/actikare.com\/central-nj\/#website"},"primaryImageOfPage":{"@id":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#primaryimage"},"image":{"@id":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#primaryimage"},"thumbnailUrl":"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg","datePublished":"2017-10-28T11:39:18+00:00","dateModified":"2018-08-16T17:44:02+00:00","description":"Recovery Care & Recovery Home Care Services.Acti-Kare of of Central New Jersey, NJ provides recovery care services for surgery, accident and other disabilities as well as recovery care assistance with meal prep, personal care, house cleaning and more to help assist you in recovery. Acti-Kare of of Central New Jersey, also provides recovery home care services in Middletown Township, Monroe Township and Princeton.","breadcrumb":{"@id":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actikare.com\/central-nj\/recovery-home-care\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#primaryimage","url":"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg","contentUrl":"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/Personal-banner.jpg","width":1349,"height":571,"caption":"Home Care Services in in Central New Jersey, NJ | In-Home Care Servicesi in Central New Jersey, NJ"},{"@type":"BreadcrumbList","@id":"https:\/\/actikare.com\/central-nj\/recovery-home-care\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/actikare.com\/central-nj\/"},{"@type":"ListItem","position":2,"name":"Recovery Care"}]},{"@type":"WebSite","@id":"https:\/\/actikare.com\/central-nj\/#website","url":"https:\/\/actikare.com\/central-nj\/","name":"Acti-Kare of Central New Jersey","description":"","publisher":{"@id":"https:\/\/actikare.com\/central-nj\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actikare.com\/central-nj\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/actikare.com\/central-nj\/#organization","name":"Acti-Kare of Central New Jersey","url":"https:\/\/actikare.com\/central-nj\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/actikare.com\/central-nj\/#\/schema\/logo\/image\/","url":"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/logo.png","contentUrl":"https:\/\/actikare.com\/central-nj\/wp-content\/uploads\/sites\/531\/2017\/10\/logo.png","width":101,"height":60,"caption":"Acti-Kare of Central New Jersey"},"image":{"@id":"https:\/\/actikare.com\/central-nj\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/pages\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":23,"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/pages\/99\/revisions"}],"predecessor-version":[{"id":875,"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/pages\/99\/revisions\/875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/media\/207"}],"wp:attachment":[{"href":"https:\/\/actikare.com\/central-nj\/wp-json\/wp\/v2\/media?parent=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}